{"id":10364,"date":"2025-01-06T15:16:01","date_gmt":"2025-01-06T15:16:01","guid":{"rendered":"https:\/\/ais-edu.pt\/?p=10364"},"modified":"2026-05-05T17:12:39","modified_gmt":"2026-05-05T17:12:39","slug":"growth-vs-fixed-mindset-and-the-pillars-of-sel","status":"publish","type":"post","link":"https:\/\/ais-edu.pt\/pt-pt\/growth-vs-fixed-mindset-and-the-pillars-of-sel\/","title":{"rendered":"Growth vs. Fixed mindset e os pilares do SEL"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<strong>No Almada International School, trabalhamos para criar um ambiente seguro e estimulante, onde as crian\u00e7as crescem n\u00e3o s\u00f3 academicamente, mas tamb\u00e9m a n\u00edvel social e emocional.<\/strong> Acreditamos que \u00e9 essencial que desenvolvam compet\u00eancias que v\u00e3o al\u00e9m do conhecimento acad\u00e9mico, como a empatia, a resili\u00eancia e a autonomia.<\/p>\n<p>Gostar\u00edamos de partilhar duas ideias fundamentais que est\u00e3o na base do nosso trabalho: Os pilares do (SEL \u2013 Social and Emotional Learning) e a diferen\u00e7a entre Growth Mindset \u00a0e Fixed Mindset.<\/p>\n<p><strong>No Almada International School, trabalhamos para criar um ambiente seguro e estimulante, onde as crian\u00e7as crescem n\u00e3o s\u00f3 academicamente, mas tamb\u00e9m a n\u00edvel social e emocional.<\/strong> Acreditamos que \u00e9 essencial que desenvolvam compet\u00eancias que v\u00e3o al\u00e9m do conhecimento acad\u00e9mico, como a empatia, a resili\u00eancia e a autonomia.<\/p>\n<p>Gostar\u00edamos de partilhar duas ideias fundamentais que est\u00e3o na base do nosso trabalho: Os pilares do (SEL \u2013 Social and Emotional Learning) e a diferen\u00e7a entre Growth Mindset \u00a0e Fixed Mindset.<\/p>\n<p><strong>O que \u00e9 o SEL?<\/strong><\/p>\n<p>O SEL \u00e9 um processo que ensina as crian\u00e7as a reconhecer e a gerir as suas emo\u00e7\u00f5es, a tomar decis\u00f5es respons\u00e1veis, a estabelecer rela\u00e7\u00f5es positivas e a lidar com os desafios de forma saud\u00e1vel.<\/p>\n<p>No contexto escolar, os pilares do SEL ajudam as crian\u00e7as a desenvolver compet\u00eancias essenciais para a vida, como:<\/p>\n<ul>\n<li><strong>Autoconsci\u00eancia<\/strong> \u2013 A autoconsci\u00eancia \u00e9 a capacidade de uma crian\u00e7a reconhecer e compreender as suas pr\u00f3prias emo\u00e7\u00f5es, pensamentos e comportamentos. Conseguir perceber como se sente em diferentes situa\u00e7\u00f5es e identificar o que est\u00e1 a acontecer dentro de si, de forma a poder reagir de maneira adequada. A autoconsci\u00eancia \u00e9 essencial para o desenvolvimento de uma autoestima saud\u00e1vel e para o autocontrolo.<\/li>\n<li><strong>Autogest\u00e3o<\/strong> \u2013 A autogest\u00e3o \u00e9 a compet\u00eancia de a crian\u00e7a gerir as suas emo\u00e7\u00f5es, pensamentos e comportamentos de forma eficaz, especialmente em situa\u00e7\u00f5es desafiantes ou stressantes. Inclui a capacidade de controlar impulsos, definir e trabalhar para atingir objetivos, lidar com a frustra\u00e7\u00e3o e manter a calma em momentos de stress. A autogest\u00e3o \u00e9 muito importante para ajudar as crian\u00e7as a tomarem decis\u00f5es mais ponderadas e a manterem-se focadas nas suas tarefas.<\/li>\n<li><strong>Consci\u00eancia Social<\/strong> \u2013 A consci\u00eancia social refere-se \u00e0 habilidade da crian\u00e7a compreender as emo\u00e7\u00f5es e necessidades dos outros. Trata-se de desenvolver empatia, ou seja, ter a capacidade de se colocar no lugar do outro. A consci\u00eancia social tamb\u00e9m envolve o respeito pelas diferen\u00e7as, a promo\u00e7\u00e3o de uma comunica\u00e7\u00e3o eficaz e a habilidade de trabalhar em grupo com coopera\u00e7\u00e3o e respeito.<\/li>\n<li><strong>Relacionamentos Saud\u00e1vei<\/strong>s \u2013 Ter relacionamentos saud\u00e1veis significa ser capaz de fazer amizades e manter boas rela\u00e7\u00f5es com os pares, tratando-os com respeito e gentileza. As crian\u00e7as que conseguem criar bons relacionamentos s\u00e3o capazes de comunicar clara e assertivamente o que sentem e pensam, e sabem ouvir os outros tamb\u00e9m.<\/li>\n<li><strong>Tomada de Decis\u00e3o Respons\u00e1vel<\/strong> \u2013 \u00c9 a capacidade de a crian\u00e7a tomar decis\u00f5es baseadas em valores \u00e9ticos, tendo em conta as consequ\u00eancias das suas a\u00e7\u00f5es para si e para os outros.<\/li>\n<\/ul>\n<p>Estes pilares s\u00e3o fundamentais para o desenvolvimento de compet\u00eancias emocionais. Em conjunto com o ensino acad\u00e9mico, ajudam as crian\u00e7as a viver o mundo com confian\u00e7a, empatia e resili\u00eancia.<\/p>\n<p><strong>Growth Mindset vs Fixed Mindset: A Mentalidade que forma o Futuro<\/strong><\/p>\n<p>Hoje, gostar\u00edamos de nos focar especialmente na diferen\u00e7a entre Growth Mindset\u00a0 e Fixed Mindset.<\/p>\n<p><strong>O que \u00e9 Fixed Mindset?<\/strong><\/p>\n<p>O Fixed Mindset \u00e9 a cren\u00e7a de que as habilidades e intelig\u00eancia s\u00e3o naturais e n\u00e3o podem ser mudadas ou melhoradas. Crian\u00e7as com mentalidade fixa tendem a evitar desafios e podem sentir-se desmotivadas quando erram, acreditando que n\u00e3o s\u00e3o \u201cboas\u201d o suficiente para melhorar em algo.<\/p>\n<p>Exemplo de uma crian\u00e7a com Fixed Mindset: \u201cEu n\u00e3o sou bom em matem\u00e1tica, nunca vou ser.\u201d<\/p>\n<p><strong>Como a mentalidade fixa pode limitar o potencial da crian\u00e7a?<\/strong><\/p>\n<ul>\n<li><strong>Evita desafios:<\/strong> A crian\u00e7a pode preferir tarefas f\u00e1ceis, onde n\u00e3o tem risco de falhar.<\/li>\n<li><strong>Desmotiva diante de erros:<\/strong> Em vez de aprender com os erros, a crian\u00e7a pode desmotivar e desistir facilmente.<\/li>\n<li><strong>Foco nas compara\u00e7\u00f5es:<\/strong> Crian\u00e7as com mentalidade fixa podem sentir-se inferiorizadas quando se comparam com os outros.<\/li>\n<\/ul>\n<p><strong>O que \u00e9 o Growth Mindset?<\/strong><\/p>\n<p>O Growth Mindset \u00e9 a cren\u00e7a de que as habilidades e intelig\u00eancia podem ser desenvolvidas atrav\u00e9s de esfor\u00e7o, dedica\u00e7\u00e3o e aprendizagem cont\u00ednua. Quando uma crian\u00e7a adota uma mentalidade de crescimento, ela v\u00ea os desafios como oportunidades para aprender e melhorar. Se falhar, entende que o erro faz parte do processo e que pode sempre tentar outra vez e melhorar.<\/p>\n<p>Exemplo de uma crian\u00e7a com Growth Mindset: \u201cEu n\u00e3o consegui resolver este problema hoje, mas com mais pr\u00e1tica e esfor\u00e7o, vou conseguir!\u201d<\/p>\n<p><strong>Como podemos ajudar os nossos filhos a desenvolverem uma mentalidade de crescimento?<\/strong><\/p>\n<ul>\n<li><strong>Encorajando o esfor\u00e7o:<\/strong> O foco deve estar no esfor\u00e7o que a crian\u00e7a faz e n\u00e3o apenas no resultado. Devemos elogiar o esfor\u00e7o e a persist\u00eancia da crian\u00e7a.<\/li>\n<li><strong>Aceitar os erros como parte da aprendizagem:<\/strong> Ensinar a crian\u00e7a que errar n\u00e3o \u00e9 um problema, mas sim uma oportunidade para aprender.<\/li>\n<li><strong>Fazer perguntas abertas:<\/strong> Estimular a crian\u00e7a a refletir sobre como pode fazer as coisas de forma diferente da pr\u00f3xima vez.<\/li>\n<li><strong>Fazer elogios inteligentes:<\/strong> Elogiar o processo e n\u00e3o apenas o talento. \u201cEstou muito orgulhoso(a) de como continuaste a tentar, apesar das dificuldades\u201d.<\/li>\n<\/ul>\n<p>O SEL e o Growth Mindset s\u00e3o componentes cruciais no desenvolvimento das crian\u00e7as. Ao incentivarmos uma mentalidade de crescimento, estamos a preparar as nossas crian\u00e7as para uma vida de aprendizagem cont\u00ednua, supera\u00e7\u00e3o de desafios e constru\u00e7\u00e3o de rela\u00e7\u00f5es saud\u00e1veis e positivas.<\/p>\n<p><strong>No nosso trabalho di\u00e1rio, procuramos integrar estas abordagens em todas as atividades escolares e intera\u00e7\u00f5es, para que as crian\u00e7as se sintam apoiadas e motivadas a crescer tanto a n\u00edvel acad\u00e9mico como emocional.<\/strong><\/p>\n<p>Estamos dispon\u00edveis para apoiar as fam\u00edlias em casa com dicas pr\u00e1ticas sobre como cultivar o Growth Mindset e outras compet\u00eancias de SEL.<\/p>\n<p>Fiquem atentos \u00e0s pr\u00f3ximas newsletters para mais recursos e informa\u00e7\u00f5es![\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>We want to share two fundamental ideas that underlie our work: The pillars of SEL and the difference between a Growth Mindset and a Fixed Mindset.<\/p>\n","protected":false},"author":1,"featured_media":10363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":{"0":"post-10364","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-wellbeing"},"_links":{"self":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/posts\/10364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/comments?post=10364"}],"version-history":[{"count":4,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/posts\/10364\/revisions"}],"predecessor-version":[{"id":10369,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/posts\/10364\/revisions\/10369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/media\/10363"}],"wp:attachment":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/media?parent=10364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/categories?post=10364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/tags?post=10364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}