{"id":10271,"date":"2025-12-31T12:22:38","date_gmt":"2025-12-31T12:22:38","guid":{"rendered":"https:\/\/ais-edu.pt\/contactos\/"},"modified":"2026-04-27T12:12:33","modified_gmt":"2026-04-27T12:12:33","slug":"contactos","status":"publish","type":"page","link":"https:\/\/ais-edu.pt\/pt-pt\/contactos\/","title":{"rendered":"Contactos"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; top_padding_phone=&#8221;4%&#8221; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#FFFFFF&#8221; shape_divider_position=&#8221;both&#8221; shape_divider_height=&#8221;100&#8243; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;js&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;parallax&#8221; animation_movement_type=&#8221;transform_x&#8221; column_parallax_intensity=&#8221;0.5&#8243; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;5&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;none&#8221; font_style=&#8221;h1&#8243; stagger_animation=&#8221;true&#8221; mobile_disable_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Contactos&#8221; text_direction=&#8221;default&#8221; font_size=&#8221;45&#8243; font_size_phone=&#8221;37&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][nectar_responsive_text inherited_font_style=&#8221;h2&#8243; text_color=&#8221;#949DAE&#8221; font_size_desktop=&#8221;30&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;27&#8243; font_line_height=&#8221;1.1&#8243;]\n<h2>Almada International School<\/h2>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"elementor-element elementor-element-73320205 elementor-widget elementor-widget-text-editor\" data-id=\"73320205\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Valorizamos a <b>comunica\u00e7\u00e3o com os nossos alunos, fam\u00edlias e comunidade<\/b>. Seja para <b>esclarecer uma quest\u00e3o, partilhar uma sugest\u00e3o ou dar feedback<\/b>, convidamo-lo a <b>entrar em contacto connosco<\/b>. <\/p>\n<p>A nossa equipa est\u00e1 dispon\u00edvel para <b>responder de forma c\u00e9lere e eficaz<\/b>, garantindo um acompanhamento pr\u00f3ximo e atento. Acreditamos que uma <b>comunica\u00e7\u00e3o aberta e transparente<\/b> \u00e9 essencial para construir uma<br \/><b>comunidade escolar forte, pr\u00f3xima e din\u00e2mica.<\/b> <\/p>\n<p>Utilize os <b>contactos dispon\u00edveis<\/b> para falar connosco. <b>Teremos todo o gosto em ajudar<\/b>. <\/p>\n<\/div>\n<\/div>\n[\/nectar_responsive_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-xs&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#949DAE&#8221; font_size_desktop=&#8221;24&#8243; font_size_tablet=&#8221;22px&#8221; font_line_height=&#8221;1.3&#8243; text_direction=&#8221;default&#8221;]\n<h3>Localiza\u00e7\u00e3o<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"elementor-element elementor-element-73320205 elementor-widget elementor-widget-text-editor\" data-id=\"73320205\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4781f510\" data-id=\"4781f510\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-4aa46e9 elementor-widget elementor-widget-heading\" data-id=\"4aa46e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<p class=\"elementor-heading-title elementor-size-default\">Azinhaga da Urraca, n\u00ba1<br \/>\n2815-619 Sobreda, Portugal<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243; custom_height_phone=&#8221;0&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#949DAE&#8221; font_size_desktop=&#8221;24&#8243; font_size_tablet=&#8221;22px&#8221; font_line_height=&#8221;1.3&#8243; text_direction=&#8221;default&#8221;]\n<h3>Contactos<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"elementor-element elementor-element-73320205 elementor-widget elementor-widget-text-editor\" data-id=\"73320205\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4781f510\" data-id=\"4781f510\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-4aa46e9 elementor-widget elementor-widget-heading\" data-id=\"4aa46e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">+351 215 954 395<\/div>\n<div class=\"elementor-element elementor-element-4aa46e9 elementor-widget elementor-widget-heading\" data-id=\"4aa46e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><a href=\"mailto:info@ais-edu.pt\">info@ais-edu.pt<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243; custom_height_phone=&#8221;20&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-xs&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#949DAE&#8221; font_size_desktop=&#8221;24&#8243; font_size_tablet=&#8221;22px&#8221; font_line_height=&#8221;1.3&#8243; text_direction=&#8221;default&#8221;]\n<h3>Admisso\u00f5es<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"elementor-element elementor-element-73320205 elementor-widget elementor-widget-text-editor\" data-id=\"73320205\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4781f510\" data-id=\"4781f510\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-4aa46e9 elementor-widget elementor-widget-heading\" data-id=\"4aa46e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-element elementor-element-73320205 elementor-widget elementor-widget-text-editor\" data-id=\"73320205\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4781f510\" data-id=\"4781f510\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div data-id=\"4aa46e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><a href=\"mailto:admissions@ais-edu.pt\">admissions@ais-edu.pt<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243; custom_height_phone=&#8221;0&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#949DAE&#8221; font_size_desktop=&#8221;24&#8243; font_size_tablet=&#8221;22px&#8221; font_line_height=&#8221;1.3&#8243; text_direction=&#8221;default&#8221;]\n<h3>Fa\u00e7a parte da nossa equipa<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"elementor-element elementor-element-73320205 elementor-widget elementor-widget-text-editor\" data-id=\"73320205\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4781f510\" data-id=\"4781f510\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div data-id=\"4aa46e9\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><a href=\"mailto:joinourteam@ais-edu.pt\">joinourteam@ais-edu.pt<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243; custom_height_phone=&#8221;20&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-xs&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#949DAE&#8221; font_size_desktop=&#8221;24&#8243; font_size_tablet=&#8221;22px&#8221; font_line_height=&#8221;1.3&#8243; text_direction=&#8221;default&#8221;]\n<h3>Hor\u00e1rio<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221;]\n<div class=\"elementor-element elementor-element-73320205 elementor-widget elementor-widget-text-editor\" data-id=\"73320205\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4781f510\" data-id=\"4781f510\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-3750fb00 elementor-widget elementor-widget-text-editor\" data-id=\"3750fb00\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e4e69a0\" data-id=\"1e4e69a0\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-70de781a elementor-widget elementor-widget-text-editor\" data-id=\"70de781a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div>\n<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2d751b68\" data-id=\"2d751b68\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-510126da elementor-widget elementor-widget-heading\" data-id=\"510126da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\"><\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-7f636977 elementor-widget elementor-widget-text-editor\" data-id=\"7f636977\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>08:00 \u2013 18:00<br \/>\n2\u00aa feira \u2013 6\u00aa feira<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243; custom_height_phone=&#8221;0&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#949DAE&#8221; font_size_desktop=&#8221;24&#8243; font_size_tablet=&#8221;22px&#8221; font_line_height=&#8221;1.3&#8243; text_direction=&#8221;default&#8221;]\n<h3>Siga-nos<\/h3>\n[\/nectar_responsive_text][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;custom&#8221; icon_color_custom=&#8221;#1D2C4E&#8221; icon_color_custom_hover=&#8221;#1877F2&#8243; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;5px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-facebook-square&#8221; icon_size=&#8221;28&#8243; url=&#8221;https:\/\/www.facebook.com\/AlmadaInternationalSchool&#8221;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;custom&#8221; icon_color_custom=&#8221;#1D2C4E&#8221; icon_color_custom_hover=&#8221;#E1306C&#8221; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;5px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-instagram&#8221; icon_size=&#8221;28&#8243; url=&#8221;https:\/\/www.instagram.com\/almadainternational\/&#8221;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;custom&#8221; icon_color_custom=&#8221;#1D2C4E&#8221; icon_color_custom_hover=&#8221;#0A66C2&#8243; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;5px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-linkedin-square&#8221; icon_size=&#8221;28&#8243; url=&#8221;https:\/\/www.linkedin.com\/company\/almada-international-school\/&#8221;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;custom&#8221; icon_color_custom=&#8221;#1D2C4E&#8221; icon_color_custom_hover=&#8221;#FF0000&#8243; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;5px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-youtube-play&#8221; icon_size=&#8221;28&#8243; url=&#8221;https:\/\/www.youtube.com\/@almadainternationalschool\/featured&#8221;][nectar_icon icon_family=&#8221;fontawesome&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;custom&#8221; icon_color_custom=&#8221;#1D2C4E&#8221; icon_color_custom_hover=&#8221;#1ED760&#8243; open_new_tab=&#8221;true&#8221; icon_padding=&#8221;5px&#8221; pointer_events=&#8221;all&#8221; icon_fontawesome=&#8221;fa fa-spotify&#8221; icon_size=&#8221;28&#8243; url=&#8221;https:\/\/podcasters.spotify.com\/pod\/show\/almadainternationalschool\/&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243; custom_height_phone=&#8221;0&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8350&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;20px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;7%&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; top_padding_phone=&#8221;4%&#8221; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#FFFFFF&#8221; shape_divider_position=&#8221;both&#8221; shape_divider_height=&#8221;100&#8243; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-5-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;js&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;parallax&#8221; animation_movement_type=&#8221;transform_x&#8221; column_parallax_intensity=&#8221;0.5&#8243; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_raw_html css=&#8221;&#8221;]PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3Lmdvb2dsZS5jb20vbWFwcy9lbWJlZD9wYj0hMW0xNCExbTghMW0zITFkMjA1OTYuMDQ1ODc1ODY5MTQ2ITJkLTkuMTkyODU0OTMyOTcyNDg3ITNkMzguNjY4NzE5NjExODk1NCEzbTIhMWkxMDI0ITJpNzY4ITRmMTMuMSEzbTMhMW0yITFzMHhkMWVjYjE0MjA4OWNjNDclM0EweDUzYTE3YmYxYTM5ZDE2OWIhMnNBbG1hZGElMjBJbnRlcm5hdGlvbmFsJTIwU2Nob29sITVlMCEzbTIhMXNwdC1QVCEyc3B0ITR2MTc2OTE4MTcyNDQ5MiE1bTIhMXNwdC1QVCEyc3B0IiB3aWR0aD0iNjAwIiBoZWlnaHQ9IjM1MCIgc3R5bGU9ImJvcmRlcjowOyIgYWxsb3dmdWxsc2NyZWVuPSIiIGxvYWRpbmc9ImxhenkiIHJlZmVycmVycG9saWN5PSJuby1yZWZlcnJlci13aGVuLWRvd25ncmFkZSI+PC9pZnJhbWU+[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-xs&#8221;][vc_raw_html css=&#8221;&#8221;]PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3Lmdvb2dsZS5jb20vbWFwcy9lbWJlZD9wYj0hMW0xNCExbTghMW0zITFkMjA1OTYuMDQ1ODc1ODY5MTQ2ITJkLTkuMTkyODU0OTMyOTcyNDg3ITNkMzguNjY4NzE5NjExODk1NCEzbTIhMWkxMDI0ITJpNzY4ITRmMTMuMSEzbTMhMW0yITFzMHhkMWVjYjE0MjA4OWNjNDclM0EweDUzYTE3YmYxYTM5ZDE2OWIhMnNBbG1hZGElMjBJbnRlcm5hdGlvbmFsJTIwU2Nob29sITVlMCEzbTIhMXNwdC1QVCEyc3B0ITR2MTc2OTE4MTcyNDQ5MiE1bTIhMXNwdC1QVCEyc3B0IiB3aWR0aD0iMTkwMCIgaGVpZ2h0PSI4MjAiIHN0eWxlPSJib3JkZXI6MDsiIGFsbG93ZnVsbHNjcmVlbj0iIiBsb2FkaW5nPSJsYXp5IiByZWZlcnJlcnBvbGljeT0ibm8tcmVmZXJyZXItd2hlbi1kb3duZ3JhZGUiPjwvaWZyYW1lPg==[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;100&#8243;][nectar_responsive_text inherited_font_style=&#8221;h2&#8243; text_color=&#8221;#1D2C4E&#8221; font_size_desktop=&#8221;30&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;27&#8243; font_line_height=&#8221;1.1&#8243;]\n<h2>Siga-nos no Instagram<\/h2>\n[\/nectar_responsive_text][vc_raw_html css=&#8221;&#8221;]W2luc3RhZ3JhbS1mZWVkIGZlZWQ9IjIiXQ==[\/vc_raw_html][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; left_padding_desktop=&#8221;4%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4%&#8221; top_padding_phone=&#8221;4%&#8221; left_padding_phone=&#8221;0&#8243; right_padding_phone=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#FFFFFF&#8221; shape_divider_position=&#8221;both&#8221; shape_divider_height=&#8221;100&#8243; bg_image_animation=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10271","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/comments?post=10271"}],"version-history":[{"count":2,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10271\/revisions"}],"predecessor-version":[{"id":10275,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10271\/revisions\/10275"}],"wp:attachment":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/media?parent=10271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}