{"id":10247,"date":"2025-08-30T10:53:41","date_gmt":"2025-08-30T10:53:41","guid":{"rendered":"https:\/\/ais-edu.pt\/primary\/"},"modified":"2026-04-27T12:02:26","modified_gmt":"2026-04-27T12:02:26","slug":"primary","status":"publish","type":"page","link":"https:\/\/ais-edu.pt\/pt-pt\/primary\/","title":{"rendered":"Primary"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;none&#8221; font_style=&#8221;h1&#8243; stagger_animation=&#8221;true&#8221; mobile_disable_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Primary Years&#8221; text_direction=&#8221;default&#8221; font_size=&#8221;50&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; bottom_padding_phone=&#8221;15%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;20px&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;8846&#8243; background_image_type=&#8221;default&#8221; background_image_position=&#8221;center bottom&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;50px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;very_subtle&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60vh&#8221; custom_height_tablet=&#8221;70vh&#8221; custom_height_phone=&#8221;50vh&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; bottom_padding_phone=&#8221;15%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;20px&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_2=&#8221;yes&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#46BDD0&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;50px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_scrolling_text scroll_direction=&#8221;ltr&#8221; scroll_speed=&#8221;slower&#8221; text_repeat_number=&#8221;8&#8243; text_repeat_divider=&#8221;space&#8221; text_space_amount=&#8221;medium&#8221; mask_edges=&#8221;yes&#8221; style=&#8221;default&#8221; outline_applies_to=&#8221;text_only&#8221; overflow=&#8221;hidden&#8221; background_image_animation=&#8221;None&#8221; custom_font_size=&#8221;16&#8243;]\n<div class=\"wpb_wrapper\">\n<div class=\"nectar-responsive-text font_size_desktop_15px nectar-link-underline-effect\">\n<p><strong>FROM 6 TO 10 YEARS OLD | WHERE CURIOSITY BEGINS AND CONFIDENCE GROWS |<\/strong><\/p>\n<\/div>\n<\/div>\n[\/nectar_scrolling_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;7%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;7%&#8221; bottom_padding_phone=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;38&#8243; font_line_height=&#8221;1.2&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;33&#8243;]\n<h2>Cultivar Mentes Curiosas<\/h2>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_min=&#8221;14px&#8221; font_size_max=&#8221;20px&#8221; font_line_height=&#8221;1.5&#8243; text_direction=&#8221;default&#8221;]<b>O nosso programa para os Anos do Primary<\/b> foi concebido para proporcionar experi\u00eancias<br \/>\nde <b>aprendizagem estimulantes e envolventes<\/b> numa fase determinante do desenvolvimento.<br \/>\n <br \/>Sabemos que <b>estes anos s\u00e3o fundamentais para o crescimento acad\u00e9mico e pessoal.<\/b> Por<br \/>isso, a nossa abordagem vai al\u00e9m dos conte\u00fados, promovendo o desenvolvimento integral<br \/>de cada aluno.[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;2&#8243; desktop_small_cols_flickity=&#8221;1&#8243; tablet_cols_flickity=&#8221;1&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_subtract_from_column_width=&#8221;10&#8243; flickity_controls=&#8221;default&#8221; color=&#8221;extra-color-2&#8243; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; pagination_alignment_flickity=&#8221;default&#8221; flickity_spacing=&#8221;default&#8221; flickity_column_vertical_alignment=&#8221;middle&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;default&#8221; flickity_image_scale_on_drag=&#8221;true&#8221; flickity_adaptive_height=&#8221;true&#8221; column_color=&#8221;#F8F8F8&#8243; border_radius=&#8221;5px&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766277477-10&#8243; tab_id=&#8221;1776766277478-8&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#CAA2C2&#8243; color_box_hover_overlay_opacity=&#8221;0.9&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;none&#8221;]\n<h3><b>O Porqu\u00ea<\/b><\/h3>\n<p><b>Uma etapa decisiva da aprendizagem<\/b><br \/>\nOs anos do Primary estabelecem as bases da confian\u00e7a, da curiosidade e de uma aprendizagem para a vida.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766277514-1&#8243; tab_id=&#8221;1776766277514-4&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#BF6262&#8243; color_box_hover_overlay_opacity=&#8221;0.9&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221;]\n<h3>O Curr\u00edculo<\/h3>\n<p><b>Um curr\u00edculo equilibrado e abrangente<\/b><br \/>\nCombinamos bases acad\u00e9micas s\u00f3lidas com o desenvolvimento social e emocional,<br \/>promovendo um crescimento harmonioso e completo.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766277538-0&#8243; tab_id=&#8221;1776766277538-6&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#AFA22C&#8221; color_box_hover_overlay_opacity=&#8221;0.9&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221;]\n<h3>Aprendentes Ativos<\/h3>\n<p>A crian\u00e7a no centro da aprendizagem<br \/>A nossa abordagem incentiva cada aluno a assumir um papel ativo no seu percurso,<br \/>participando de forma consciente e envolvida.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766277555-0&#8243; tab_id=&#8221;1776766277555-2&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#A3AE78&#8243; color_box_hover_overlay_opacity=&#8221;0.9&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221;]\n<h3>Os Professores<\/h3>\n<p><b>Educadores experientes e dedicados<\/b><br \/>\nA nossa equipa orienta, apoia e inspira, criando um ambiente de aprendizagem seguro, motivador e exigente.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766277579-2&#8243; tab_id=&#8221;1776766277579-4&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#94ACA4&#8243; color_box_hover_overlay_opacity=&#8221;0.9&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221;]\n<h3>O Resultado<\/h3>\n<p><b>O prazer de descobrir e explorar<\/b><br \/>\nCultivamos curiosidade, autonomia e um entusiasmo genu\u00edno pelo conhecimento.[\/fancy_box][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;hidden&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;top&#8221; shape_divider_height=&#8221;50%&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; flexbox_justify_content_tablet=&#8221;&#8221; flexbox_align_items_tablet=&#8221;&#8221; flexbox_direction_tablet=&#8221;&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;3%&#8221; left_padding_desktop=&#8221;7%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;7%&#8221; bottom_padding_tablet=&#8221;6%&#8221; left_padding_tablet=&#8221;25px&#8221; right_padding_tablet=&#8221;40%&#8221; left_padding_phone=&#8221;25px&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;25px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner right_padding_desktop=&#8221;8%&#8221; right_padding_phone=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;advanced&#8221; content_layout=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;38&#8243; font_size_phone=&#8221;33&#8243; font_line_height=&#8221;1.1&#8243;]\n<h2>Aprender Atrav\u00e9s do Brincar<\/h2>\n[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;4&#8243; desktop_small_cols_flickity=&#8221;3&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_subtract_from_column_width=&#8221;80px&#8221; flickity_controls=&#8221;none&#8221; color=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_spacing=&#8221;10px&#8221; flickity_centered_cells=&#8221;true&#8221; flickity_column_vertical_alignment=&#8221;default&#8221; column_padding=&#8221;20px&#8221; flickity_element_spacing=&#8221;0&#8243; border_radius=&#8221;10px&#8221; autorotate=&#8221;true&#8221; autorotate_type=&#8221;ticker&#8221; ticker_speed=&#8221;slow&#8221; ticker_direction=&#8221;default&#8221; flickity_autorotate_pause_on_hover=&#8221;true&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_url=&#8221;8878&#8243; flickity_bg_image_loading=&#8221;lazy-load&#8221; flickity_background_image_gradient_blur=&#8221;true&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; color_layer_gradient_direction=&#8221;left_to_right&#8221; id=&#8221;1776766277670-4&#8243; title=&#8221;Item&#8221; content_layout=&#8221;flexbox&#8221; advanced_gradient_display_type=&#8221;linear&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; tab_id=&#8221;1776766277670-6&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;350px&#8221; custom_height_phone=&#8221;250px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;8px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;0.9&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#1D2C4E&#8221; text_direction=&#8221;default&#8221;]\n<h3>Metodologias Ativas<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_min=&#8221;14px&#8221; font_size_max=&#8221;20px&#8221; font_size_desktop=&#8221;1.1vw&#8221; font_line_height=&#8221;1.5&#8243; text_direction=&#8221;default&#8221;]No AIS, a aprendizagem \u00e9 din\u00e2mica e pr\u00e1tica, com uma abordagem ativa presente em todas as \u00e1reas do curr\u00edculo.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_url=&#8221;8880&#8243; flickity_bg_image_loading=&#8221;lazy-load&#8221; flickity_background_image_gradient_blur=&#8221;true&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; advanced_gradient=&#8221;linear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,0) 36%)&#8221; advanced_gradient_opacity=&#8221;0.2&#8243; advanced_gradient_opacity_hover=&#8221;0.2&#8243; color_layer_opacity=&#8221;&#8221; color_layer_opacity_hover=&#8221;&#8221; color_layer=&#8221;linear-gradient(274deg, rgb(255, 96, 96) 10%, #f3f3f3 90%)&#8221; color_layer_gradient_angle=&#8221;274&#8243; color_layer_gradient_radial_position=&#8221;top right&#8221; color_layer_gradient_direction=&#8221;left_b_to_right_t&#8221; id=&#8221;1776766277717-3&#8243; title=&#8221;Item&#8221; color_layer_gradient_type=&#8221;radial&#8221; advanced_gradient_display_type=&#8221;linear&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; tab_id=&#8221;1776766277717-2&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;350px&#8221; custom_height_phone=&#8221;250px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;8px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;0.9&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#1D2C4E&#8221; text_direction=&#8221;default&#8221;]\n<h3>Aprendizagem ao Ar Livre<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_min=&#8221;14px&#8221; font_size_max=&#8221;20px&#8221; font_size_desktop=&#8221;1.1vw&#8221; font_line_height=&#8221;1.5&#8243; text_direction=&#8221;default&#8221;]Nos Anos do Primary, a aprendizagem vai al\u00e9m da sala de aula, integrando experi\u00eancias ao ar livre que assumem um papel significativo no desenvolvimento dos alunos.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_url=&#8221;8825&#8243; flickity_bg_image_loading=&#8221;lazy-load&#8221; flickity_background_image_gradient_blur=&#8221;true&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; advanced_gradient=&#8221;linear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,0) 37%)&#8221; advanced_gradient_opacity=&#8221;0.2&#8243; advanced_gradient_opacity_hover=&#8221;0.2&#8243; color_layer_gradient_direction=&#8221;left_to_right&#8221; id=&#8221;1776766277754-10&#8243; title=&#8221;Item&#8221; content_layout=&#8221;flexbox&#8221; advanced_gradient_display_type=&#8221;linear&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; tab_id=&#8221;1776766277754-3&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;350px&#8221; custom_height_phone=&#8221;250px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;8px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;0.9&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#1D2C4E&#8221; text_direction=&#8221;default&#8221;]\n<h3>Pensamento Cr\u00edtico<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_min=&#8221;14px&#8221; font_size_max=&#8221;20px&#8221; font_size_desktop=&#8221;1.1vw&#8221; font_line_height=&#8221;1.5&#8243; text_direction=&#8221;default&#8221;]Atrav\u00e9s de disciplinas como Matem\u00e1tica, Ci\u00eancias e Global Perspectives, os alunos desenvolvem racioc\u00ednio, capacidade de resolu\u00e7\u00e3o de problemas e pensamento reflexivo.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_url=&#8221;2436&#8243; flickity_bg_image_loading=&#8221;lazy-load&#8221; flickity_background_image_gradient_blur=&#8221;true&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; advanced_gradient=&#8221;linear-gradient(0deg, rgb(0,0,0) 0%, rgba(0,0,0,0) 36%)&#8221; advanced_gradient_opacity=&#8221;0.2&#8243; advanced_gradient_opacity_hover=&#8221;0.2&#8243; color_layer_opacity=&#8221;&#8221; color_layer_opacity_hover=&#8221;&#8221; color_layer=&#8221;linear-gradient(274deg, rgb(255, 96, 96) 10%, #f3f3f3 90%)&#8221; color_layer_gradient_angle=&#8221;274&#8243; color_layer_gradient_radial_position=&#8221;top right&#8221; color_layer_gradient_direction=&#8221;left_b_to_right_t&#8221; id=&#8221;1776766277806-7&#8243; title=&#8221;Item&#8221; color_layer_gradient_type=&#8221;radial&#8221; advanced_gradient_display_type=&#8221;linear&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; tab_id=&#8221;1776766277806-8&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;350px&#8221; custom_height_phone=&#8221;250px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;8px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;0.9&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#1D2C4E&#8221; text_direction=&#8221;default&#8221;]\n<h3>Compet\u00eancias de Comunica\u00e7\u00e3o<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_min=&#8221;14px&#8221; font_size_max=&#8221;20px&#8221; font_size_desktop=&#8221;1.1vw&#8221; font_line_height=&#8221;1.5&#8243; text_direction=&#8221;default&#8221;]Uma abordagem multidisciplinar fortalece compet\u00eancias de comunica\u00e7\u00e3o s\u00f3lidas, promovendo a express\u00e3o clara e eficaz em diferentes \u00e1reas do conhecimento.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_url=&#8221;2280&#8243; flickity_bg_image_loading=&#8221;lazy-load&#8221; flickity_background_image_gradient_blur=&#8221;true&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; color_layer_gradient_direction=&#8221;left_to_right&#8221; id=&#8221;1776766277846-5&#8243; title=&#8221;Item&#8221; content_layout=&#8221;flexbox&#8221; advanced_gradient_display_type=&#8221;linear&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; tab_id=&#8221;1776766277846-0&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;350px&#8221; custom_height_phone=&#8221;250px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;8px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;0.9&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#1D2C4E&#8221; text_direction=&#8221;default&#8221;]\n<h3>Express\u00e3o Criativa<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_min=&#8221;14px&#8221; font_size_max=&#8221;20px&#8221; font_size_desktop=&#8221;1.1vw&#8221; font_line_height=&#8221;1.5&#8243; text_direction=&#8221;default&#8221;]A arte, a m\u00fasica, o teatro e a explora\u00e7\u00e3o criativa permitem que os alunos se expressem livremente e descubram novas formas de pensar e interpretar o mundo.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_url=&#8221;8884&#8243; flickity_bg_image_loading=&#8221;lazy-load&#8221; flickity_background_image_gradient_blur=&#8221;true&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; color_layer_gradient_direction=&#8221;left_to_right&#8221; id=&#8221;1776766277878-0&#8243; title=&#8221;Item&#8221; content_layout=&#8221;flexbox&#8221; advanced_gradient_display_type=&#8221;linear&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221; tab_id=&#8221;1776766277879-7&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;350px&#8221; custom_height_phone=&#8221;250px&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;8px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;0.9&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;20px&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#1D2C4E&#8221; text_direction=&#8221;default&#8221;]\n<h3>Corpos Saud\u00e1veis<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_min=&#8221;14px&#8221; font_size_max=&#8221;20px&#8221; font_size_desktop=&#8221;1.1vw&#8221; font_line_height=&#8221;1.5&#8243; text_direction=&#8221;default&#8221;]Promovemos o bem-estar atrav\u00e9s do movimento e da atividade f\u00edsica regular, com tr\u00eas aulas semanais de 45 minutos de Educa\u00e7\u00e3o F\u00edsica.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;1%&#8221; left_padding_desktop=&#8221;7%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; row_name=&#8221;Sign Up Steps&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;5%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;38&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;33&#8243; font_line_height=&#8221;1.1&#8243;]\n<h2>Phonics no Primary<\/h2>\n[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][nectar_icon_list animate=&#8221;true&#8221; color=&#8221;default&#8221; direction=&#8221;horizontal&#8221; columns=&#8221;3&#8243; icon_size=&#8221;small&#8221; icon_style=&#8221;border&#8221;][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1776766277964-9&#8243; header=&#8221;Um Marco Fundamental&#8221; text=&#8221;Aprender a ler e a escrever \u00e9 uma das etapas mais determinantes da educa\u00e7\u00e3o inicial de cada crian\u00e7a.&#8221; tab_id=&#8221;1776766277964-7&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1776766277973-10&#8243; header=&#8221;Respeito pelas Etapas de Desenvolvimento&#8221; text=&#8221;Acompanhamos cada aluno na transi\u00e7\u00e3o do Kindergarten para o Primary, respeitando o seu ritmo individual e as suas necessidades espec\u00edficas.&#8221; tab_id=&#8221;1776766277974-6&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1776766277978-5&#8243; header=&#8221;Aprendizagem Atrav\u00e9s do Brincar&#8221; text=&#8221;O percurso de literacia come\u00e7a desde cedo, atrav\u00e9s de atividades l\u00fadicas que despertam interesse e envolvimento.&#8221; tab_id=&#8221;1776766277978-6&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1776766277982-1&#8243; header=&#8221;Introdu\u00e7\u00e3o Estruturada&#8221; text=&#8221;A consci\u00eancia fonol\u00f3gica \u00e9 formalmente introduzida no Kindergarten 5Y, estabelecendo bases s\u00f3lidas para a leitura e a escrita.&#8221; tab_id=&#8221;1776766277982-1&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1776766277987-7&#8243; header=&#8221;Pr\u00e1tica Di\u00e1ria&#8221; text=&#8221;A partir do Primary Year 1, os alunos consolidam as suas compet\u00eancias atrav\u00e9s de aulas di\u00e1rias de Phonics, integradas num curr\u00edculo rico de l\u00edngua inglesa.&#8221; tab_id=&#8221;1776766277987-4&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;numerical&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1776766277991-7&#8243; header=&#8221;Aprendizagem Bilingue&#8221; text=&#8221;Os alunos aprendem em ingl\u00eas, com apoio estruturado em portugu\u00eas, garantindo flu\u00eancia em ambas as l\u00ednguas e continuidade com o curr\u00edculo nacional.&#8221; tab_id=&#8221;1776766277991-7&#8243;][\/nectar_icon_list_item][\/nectar_icon_list][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;1%&#8221; left_padding_desktop=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-3-percent&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;38&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;33&#8243; font_line_height=&#8221;1.1&#8243;]\n<h2>O Detalhe que nos Distingue<\/h2>\n[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;8%&#8221; translate_y=&#8221;-20&#8243; translate_y_phone=&#8221;-45&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][carousel script=&#8221;flickity&#8221; flickity_formatting=&#8221;default&#8221; desktop_cols_flickity=&#8221;4&#8243; desktop_small_cols_flickity=&#8221;2&#8243; tablet_cols_flickity=&#8221;1&#8243; phone_cols_flickity=&#8221;1&#8243; flickity_subtract_from_column_width=&#8221;10&#8243; flickity_controls=&#8221;default&#8221; color=&#8221;extra-color-2&#8243; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; pagination_alignment_flickity=&#8221;default&#8221; flickity_spacing=&#8221;default&#8221; flickity_column_vertical_alignment=&#8221;middle&#8221; column_padding=&#8221;0&#8243; flickity_element_spacing=&#8221;default&#8221; flickity_image_scale_on_drag=&#8221;true&#8221; column_color=&#8221;#F8F8F8&#8243; border_radius=&#8221;5px&#8221;][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278115-3&#8243; tab_id=&#8221;1776766278115-5&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#000000&#8243; color_box_hover_overlay_opacity=&#8221;0.6&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;none&#8221;]\n<h3><b>As Artes<\/b><\/h3>\n<p>Incentivamos a criatividade e a express\u00e3o individual atrav\u00e9s da pintura, do teatro, da m\u00fasica, do cinema, da leitura, da fotografia e da explora\u00e7\u00e3o pr\u00e1tica, dando \u00e0s crian\u00e7as liberdade para se expressarem de forma aut\u00eantica e com significado.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278139-5&#8243; tab_id=&#8221;1776766278139-1&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_basic&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;8886&#8243; box_color_opacity=&#8221;0&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;none&#8221;][\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278163-7&#8243; tab_id=&#8221;1776766278164-3&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#000000&#8243; color_box_hover_overlay_opacity=&#8221;0.6&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221;]\n<h3><b>Educa\u00e7\u00e3o F\u00edsica<\/b><\/h3>\n<p>No Primary, asseguramos tr\u00eas aulas semanais de 45 minutos de Educa\u00e7\u00e3o F\u00edsica, promovendo h\u00e1bitos de vida saud\u00e1veis atrav\u00e9s do movimento regular e da atividade f\u00edsica estruturada.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278191-3&#8243; tab_id=&#8221;1776766278191-3&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_basic&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;8888&#8243; box_color_opacity=&#8221;0&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;none&#8221;][\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278210-5&#8243; tab_id=&#8221;1776766278210-3&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#000000&#8243; color_box_hover_overlay_opacity=&#8221;0.7&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221;]\n<h3><b>Literacia Digital<\/b><\/h3>\n<p>Num mundo em constante transforma\u00e7\u00e3o, preparamos os alunos com as compet\u00eancias digitais essenciais para o futuro. A tecnologia e a inova\u00e7\u00e3o s\u00e3o integradas como ferramentas que ampliam o envolvimento e enriquecem a aprendizagem.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278232-3&#8243; tab_id=&#8221;1776766278232-9&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_basic&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;8890&#8243; box_color_opacity=&#8221;0&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;none&#8221;][\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278258-4&#8243; tab_id=&#8221;1776766278258-8&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_hover&#8221; icon_family=&#8221;none&#8221; color=&#8221;accent-color&#8221; color_custom=&#8221;#000000&#8243; color_box_hover_overlay_opacity=&#8221;0.6&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221;]\n<h3><b>A Nossa Aldeia Global<\/b><\/h3>\n<p>Unem-nos valores partilhados, bondade, respeito, sentido de comunidade, participa\u00e7\u00e3o ativa e multiculturalidade, vividos diariamente no curr\u00edculo e na vida escolar, para al\u00e9m da origem, identidade ou l\u00edngua.[\/fancy_box][\/item][item simple_slider_bg_image_position=&#8221;default&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flickity_item_link_type=&#8221;regular&#8221; id=&#8221;1776766278282-3&#8243; tab_id=&#8221;1776766278282-9&#8243; title=&#8221;Item&#8221; content_layout=&#8221;default&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][fancy_box box_style=&#8221;color_box_basic&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;8892&#8243; box_color_opacity=&#8221;0&#8243; box_alignment=&#8221;left&#8221; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;none&#8221;][\/fancy_box][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; left_padding_desktop=&#8221;3%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;8239&#8243; image_size=&#8221;full&#8221; max_width=&#8221;110%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;20px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;1&#8243;][\/vc_column][vc_column column_padding=&#8221;padding-9-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#eaecff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;50px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1569518583590{margin-bottom: 10px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-offset-0 vc_col-md-offset-0 vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;11\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Conhe\u00e7a Guy Brikley&#8221; text_direction=&#8221;default&#8221; font_size=&#8221;40&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-lg-offset-0 vc_col-md-offset-0 vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;11\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221;]Com mais de 20 anos de experi\u00eancia na \u00e1rea da educa\u00e7\u00e3o, Guy \u00e9 um educador e l\u00edder dedicado no Ensino Prim\u00e1rio.<\/p>\n<p>\u00c9 titular de um Mestrado em Educa\u00e7\u00e3o e Desenvolvimento Internacional, com especializa\u00e7\u00e3o em envolvimento parental no contexto escolar. Ao longo da sua carreira, lecionou no Reino Unido e na \u00c1sia, acumulando uma vasta experi\u00eancia em contextos educativos internacionais. <br \/>Acredita numa abordagem hol\u00edstica da educa\u00e7\u00e3o, onde cada crian\u00e7a \u00e9 reconhecida como<br \/>um indiv\u00edduo \u00fanico, com potencial ilimitado.[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-2&#8243; animate=&#8221;yes&#8221; custom_height=&#8221;47&#8243; delay=&#8221;240&#8243;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;h6&#8243; link_type=&#8221;video_lightbox&#8221; button_color=&#8221;default&#8221; button_color_hover=&#8221;#1D2C4E&#8221; text_color=&#8221;#1D2C4E&#8221; text_color_hover=&#8221;#FFFFFF&#8221; button_border_color=&#8221;#1D2C4E&#8221; button_border_color_hover=&#8221;#1D2C4E&#8221; button_border_thickness=&#8221;2px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;center&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; font_size_desktop=&#8221;13&#8243; link_text=&#8221;HEAR FROM GUY&#8221; url=&#8221;https:\/\/www.instagram.com\/reel\/DA1Jy9PMFEo\/?utm_source=ig_web_copy_link&amp;igsh=MzRlODBiNWFlZA%3D%3D&#8221; padding_top=&#8221;12&#8243; padding_bottom=&#8221;12&#8243; padding_left=&#8221;20&#8243; padding_right=&#8221;20&#8243; margin_bottom=&#8221;15&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;5%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;5%&#8221; top_padding_phone=&#8221;10%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10247","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/comments?post=10247"}],"version-history":[{"count":2,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10247\/revisions"}],"predecessor-version":[{"id":10270,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10247\/revisions\/10270"}],"wp:attachment":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/media?parent=10247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}