{"id":10084,"date":"2025-08-25T22:21:40","date_gmt":"2025-08-25T22:21:40","guid":{"rendered":"https:\/\/ais-edu.pt\/ethos\/"},"modified":"2026-04-27T13:15:30","modified_gmt":"2026-04-27T13:15:30","slug":"ethos","status":"publish","type":"page","link":"https:\/\/ais-edu.pt\/pt-pt\/ethos\/","title":{"rendered":"Ethos"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; top_padding_phone=&#8221;10%&#8221; bottom_padding_phone=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;none&#8221; font_style=&#8221;h1&#8243; stagger_animation=&#8221;true&#8221; mobile_disable_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Nosso Ethos&#8221; text_direction=&#8221;default&#8221; font_size=&#8221;50&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; bottom_padding_phone=&#8221;15%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;20px&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;8831&#8243; background_image_type=&#8221;default&#8221; background_image_position=&#8221;center top&#8221; background_image_stacking=&#8221;default&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;50px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; mobile_disable_entrance_animation=&#8221;true&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;very_subtle&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;600&#8243; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60vh&#8221; custom_height_tablet=&#8221;70vh&#8221; custom_height_phone=&#8221;50vh&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; bottom_padding_phone=&#8221;15%&#8221; top_margin=&#8221;-5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;20px&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_2=&#8221;yes&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#132D53&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;50px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_scrolling_text scroll_direction=&#8221;ltr&#8221; scroll_speed=&#8221;slower&#8221; text_repeat_number=&#8221;8&#8243; text_repeat_divider=&#8221;space&#8221; text_space_amount=&#8221;medium&#8221; mask_edges=&#8221;yes&#8221; style=&#8221;default&#8221; outline_applies_to=&#8221;text_only&#8221; overflow=&#8221;hidden&#8221; background_image_animation=&#8221;None&#8221; custom_font_size=&#8221;16&#8243;]\n<div class=\"wpb_wrapper\">\n<div class=\"nectar-responsive-text font_size_desktop_15px nectar-link-underline-effect\">\n<p><strong>FROM THE EARLIEST YEARS TO LOWER SECONDARY | BILINGUAL EDUCATION BASED ON THE CAMBRIDGE CURRICULUM |<\/strong><\/p>\n<\/div>\n<\/div>\n[\/nectar_scrolling_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;7%&#8221; bottom_padding=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;explore&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#CFE5CE&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;300&#8243; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_phone=&#8221;20&#8243; bottom_margin_phone=&#8221;20&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;45&#8243; font_size_phone=&#8221;37&#8243; font_line_height=&#8221;1&#8243;]\n<h1 style=\"text-align: center;\">Os Valores que Moldam a Nossa Comunidade Escolar<\/h1>\n[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;No AIS, desenvolvemos um curr\u00edculo pensado para responder \u00e0s necessidades educativas de cada crian\u00e7a, promovendo a aprendizagem num contexto bilingue e valorizando a inova\u00e7\u00e3o pedag\u00f3gica. Privilegiamos o contacto com a Natureza, a descoberta da individualidade, a consci\u00eancia do meio envolvente e uma rela\u00e7\u00e3o equilibrada com o universo digital. &#8221; font_size=&#8221;1.2vw&#8221; max_width=&#8221;90%&#8221; font_line_height=&#8221;1.8&#8243; font_size_tablet=&#8221;16px&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F1F1F1&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;6%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#FFFFFF&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#FFFFFF&#8221; shape_divider_position=&#8221;both&#8221; shape_divider_height=&#8221;220&#8243; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;curve_asym&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;80px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;entrance_and_parallax&#8221; animation_movement_type=&#8221;default&#8221; column_parallax_intensity=&#8221;-0.5&#8243; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;50&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][team_member image_url=&#8221;8822&#8243; bio_image_url=&#8221;8822&#8243; team_memeber_style=&#8221;bio_fullscreen&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;html&#8221; name=&#8221;Metodologias Ativas&#8221;]Implementamos <strong>metodologias de aprendizagem ativa<\/strong>, atrav\u00e9s de um conjunto de experi\u00eancias educativas <strong>centradas nos alunos<\/strong>, promovendo a sua responsabilidade, autonomia e envolvimento. Estes processos concretizam-se atrav\u00e9s do <strong>trabalho por projetos<\/strong>, da <strong>realiza\u00e7\u00e3o de experi\u00eancias<\/strong>, da <strong>resolu\u00e7\u00e3o de problemas<\/strong>, da <strong>resposta a desafios<\/strong> e da mobiliza\u00e7\u00e3o de outras abordagens que permitem \u00e0s crian\u00e7as <strong>atribuir significado ao que aprendem<\/strong>, contextualizar novas aquisi\u00e7\u00f5es e integr\u00e1-las com outros conhecimentos. <\/p>\n<div class=\"elementor-element elementor-element-97baa5a elementor-widget elementor-widget-text-editor\" data-id=\"97baa5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Ao promover este <strong>trabalho coletivo<\/strong>, desenvolvem-se a <strong>intelig\u00eancia interpessoal<\/strong>, bem como <strong>princ\u00edpios<\/strong> e <strong>pr\u00e1ticas de colabora\u00e7\u00e3o<\/strong> e <strong>comunica\u00e7\u00e3o<\/strong>. Deste modo, s\u00e3o tamb\u00e9m incutidos os valores e <strong>din\u00e2micas da comunidade<\/strong>, assim como os <strong>princ\u00edpios da partilha<\/strong>, da <strong>igualdade<\/strong>, do <strong>respeito<\/strong> e da <strong>coopera\u00e7\u00e3o<\/strong>. <\/p>\n<\/div>\n<\/div>\n[\/team_member][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243; custom_height_phone=&#8221;10&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;26&#8243; text_direction=&#8221;default&#8221;]\n<h3>Metodologias Ativas<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16&#8243; font_line_height=&#8221;1.5&#8243;]Promovemos uma aprendizagem din\u00e2mica e significativa, centrada no aluno, que desenvolve autonomia, responsabilidade, colabora\u00e7\u00e3o e uma compreens\u00e3o s\u00f3lida do conhecimento.[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][team_member image_url=&#8221;274&#8243; bio_image_url=&#8221;274&#8243; team_memeber_style=&#8221;bio_fullscreen&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;AIS Nature &amp; Farm&#8221; team_member_bio=&#8221;O nosso espa\u00e7o exterior foi concebido para proporcionar experi\u00eancias diversificadas,&lt;br&gt;desafiantes e significativas. Num ambiente tranquilo, ativo e intencional, as crian\u00e7as exploram o espa\u00e7o ao ar livre, desenvolvendo compet\u00eancias que se refletem naturalmente no contexto de sala de aula,&lt;br&gt;promovendo uma atitude positiva perante a aprendizagem.  <\/p>\n<p>Este \u00e9 um espa\u00e7o centrado na crian\u00e7a, onde o adulto observa, acompanha e potencia, sem dirigir. Aqui, as crian\u00e7as t\u00eam tempo para brincar, explorar, reconectar-se com a Natureza, assumir riscos e viver experi\u00eancias aut\u00eanticas. &#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221;][\/team_member][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243; custom_height_phone=&#8221;10&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;26&#8243; text_direction=&#8221;default&#8221;]\n<h3>AIS Nature &amp; Farm<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16&#8243; font_line_height=&#8221;1.5&#8243;]A Nature &amp; Farm promove a curiosidade, a autonomia e a aprendizagem atrav\u00e9s de experi\u00eancias significativas ao ar livre.[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;entrance_and_parallax&#8221; animation_movement_type=&#8221;default&#8221; column_parallax_intensity=&#8221;1&#8243; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][team_member image_url=&#8221;8823&#8243; bio_image_url=&#8221;8823&#8243; team_memeber_style=&#8221;bio_fullscreen&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Curr\u00edculo Internacional&#8221; team_member_bio=&#8221;Acreditamos que um ambiente bilingue abre portas a um futuro global. No final do ensino b\u00e1sico, os alunos poder\u00e3o optar por um percurso bilingue portugu\u00eas ou por um percurso totalmente internacional, de acordo com os seus objetivos e ambi\u00e7\u00f5es. <\/p>\n<p>O AIS \u00e9 uma Cambridge Candidate School, com o objetivo de oferecer os exames IGCSE, seguidos do programa IB Diploma. Este percurso proporciona aos alunos diferentes caminhos acad\u00e9micos, alinhados com as suas aspira\u00e7\u00f5es pessoais e acad\u00e9micas. &#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221;][\/team_member][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243; custom_height_phone=&#8221;10&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;26&#8243; text_direction=&#8221;default&#8221;]\n<h3>Curr\u00edculo Internacional<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16&#8243; font_line_height=&#8221;1.5&#8243;]O nosso percurso bilingue internacional abre portas a um futuro global, sustentado por<br \/>curr\u00edculos reconhecidos internacionalmente e academicamente exigentes.[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][team_member image_url=&#8221;8827&#8243; bio_image_url=&#8221;8827&#8243; team_memeber_style=&#8221;bio_fullscreen&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Reflex\u00e3o e Consci\u00eancia&#8221; team_member_bio=&#8221;Consci\u00eancia de Si: Apoiamos os alunos no desenvolvimento da autoconsci\u00eancia, promovendo compet\u00eancias&lt;br&gt;como o pensamento cr\u00edtico, a resili\u00eancia, a colabora\u00e7\u00e3o e a gest\u00e3o de conflitos, essenciais para o seu bem-estar e equil\u00edbrio num mundo em constante mudan\u00e7a. <\/p>\n<p>Consci\u00eancia do Mundo F\u00edsico: Valorizamos o desenvolvimento socioemocional, incentivando compet\u00eancias como a comunica\u00e7\u00e3o, a coopera\u00e7\u00e3o, a perseveran\u00e7a e o pensamento cr\u00edtico, fundamentais para um&lt;br&gt;crescimento harmonioso e confiante.<\/p>\n<p>Consci\u00eancia do Mundo Digital: Integramos a tecnologia como ferramenta de aprendizagem, explorando \u00e1reas como programa\u00e7\u00e3o, pensamento computacional e rob\u00f3tica. Sempre de forma intencional, adequada \u00e0 idade e ao desenvolvimento, em ambientes seguros, estimulantes e equilibrados. &#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221;][\/team_member][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243; custom_height_phone=&#8221;10&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;26&#8243; text_direction=&#8221;default&#8221;]\n<h3> Reflex\u00e3o e Consci\u00eancia<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16&#8243; font_line_height=&#8221;1.5&#8243;]Promovemos a reflex\u00e3o cr\u00edtica e a consci\u00eancia individual, formando alunos confiantes, atentos ao mundo que os rodeia e preparados para agir com responsabilidade.[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][team_member image_url=&#8221;8833&#8243; bio_image_url=&#8221;8833&#8243; team_memeber_style=&#8221;bio_fullscreen&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Felicidade&#8221; team_member_bio=&#8221;No Almada International School, a felicidade das crian\u00e7as \u00e9 a nossa prioridade.Partilhamos com as fam\u00edlias o privil\u00e9gio de acompanhar o seu crescimento, com cuidado, inten\u00e7\u00e3o e dedica\u00e7\u00e3o. Educamos com prop\u00f3sito, apoiando o desenvolvimento f\u00edsico, intelectual e emocional de cada crian\u00e7a, num ambiente seguro, acolhedor e inspirador. &#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221;][\/team_member][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243; custom_height_phone=&#8221;10&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;26&#8243; text_direction=&#8221;default&#8221;]\n<h3>Happiness<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16&#8243; font_line_height=&#8221;1.5&#8243;]Colocamos a felicidade no centro do desenvolvimento de cada crian\u00e7a, apoiando de forma intencional o seu crescimento f\u00edsico, intelectual e emocional.[\/nectar_responsive_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;entrance_and_parallax&#8221; animation_movement_type=&#8221;default&#8221; column_parallax_intensity=&#8221;-1&#8243; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;100&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][team_member image_url=&#8221;2174&#8243; bio_image_url=&#8221;2174&#8243; team_memeber_style=&#8221;bio_fullscreen&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Bilinguismo&#8221; team_member_bio=&#8221;O nosso modelo combina o curr\u00edculo bilingue do Minist\u00e9rio da Educa\u00e7\u00e3o com o Cambridge Primary, promovendo simultaneamente a profici\u00eancia lingu\u00edstica e a consci\u00eancia intercultural.<\/p>\n<p>Procuramos desenvolver todas as dimens\u00f5es da crian\u00e7a, em articula\u00e7\u00e3o com os valores de cada fam\u00edlia.&lt;br&gt;Em todas as faixas et\u00e1rias, as turmas integram professores nativos de ingl\u00eas e de portugu\u00eas, garantindo uma exposi\u00e7\u00e3o consistente e natural a ambas as l\u00ednguas. Nas aulas de l\u00ednguas adicionais, a comunica\u00e7\u00e3o decorre exclusivamente na l\u00edngua em aprendizagem. &#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221;][\/team_member][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243; custom_height_phone=&#8221;10&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;26&#8243; text_direction=&#8221;default&#8221;]\n<h3>Bilinguismo<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16&#8243; font_line_height=&#8221;1.5&#8243;]A educa\u00e7\u00e3o bilingue fortalece a confian\u00e7a lingu\u00edstica e amplia a consci\u00eancia intercultural num ambiente de aprendizagem verdadeiramente internacional.[\/nectar_responsive_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][team_member image_url=&#8221;2168&#8243; bio_image_url=&#8221;2168&#8243; team_memeber_style=&#8221;bio_fullscreen&#8221; image_loading=&#8221;lazy-load&#8221; team_member_bio_full_html=&#8221;simple&#8221; name=&#8221;Artistic Expressions&#8221; team_member_bio=&#8221;Reconhecemos a arte como uma forma essencial de express\u00e3o humana. Promovemos a criatividade, a imagina\u00e7\u00e3o e a curiosidade atrav\u00e9s de diversas formas de express\u00e3o art\u00edstica, acompanhando todas as fases do desenvolvimento da crian\u00e7a. Atrav\u00e9s da arte, a crian\u00e7a interpreta, cria e d\u00e1 sentido ao mundo! &#8221; social_link_1=&#8221;#&#8221; social_link_2=&#8221;#&#8221; social_link_3=&#8221;#&#8221;][\/team_member][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;5&#8243; custom_height_phone=&#8221;10&#8243;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_desktop=&#8221;26&#8243; text_direction=&#8221;default&#8221;]\n<h3>Express\u00f5es Art\u00edsticas<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;16&#8243; font_line_height=&#8221;1.5&#8243;]A express\u00e3o art\u00edstica estimula a criatividade, a imagina\u00e7\u00e3o e a confian\u00e7a para comunicar atrav\u00e9s de m\u00faltiplas formas de arte.[\/nectar_responsive_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;8571&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; top_padding_phone=&#8221;10%&#8221; bottom_padding_phone=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10084","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/comments?post=10084"}],"version-history":[{"count":5,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10084\/revisions"}],"predecessor-version":[{"id":10290,"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/pages\/10084\/revisions\/10290"}],"wp:attachment":[{"href":"https:\/\/ais-edu.pt\/pt-pt\/wp-json\/wp\/v2\/media?parent=10084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}